{"id":8827,"date":"2023-08-21T17:03:23","date_gmt":"2023-08-21T15:03:23","guid":{"rendered":"https:\/\/labusadelloro.com\/?page_id=8827"},"modified":"2026-07-17T14:43:57","modified_gmt":"2026-07-17T12:43:57","slug":"la-fattoria","status":"publish","type":"page","link":"https:\/\/labusadelloro.com\/it\/la-fattoria\/","title":{"rendered":"La Fattoria"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row&#8221; full_height=&#8221;yes&#8221; equal_height=&#8221;yes&#8221; woodmart_bg_position=&#8221;center-top&#8221; css=&#8221;.vc_custom_1698503145965{margin-top: -40px !important;margin-right: 0px !important;margin-left: 0px !important;border-right-width: 10px !important;border-left-width: 10px !important;padding-top: 20px !important;padding-bottom: 20px !important;background-image: url(https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/chi-siamo.jpg?id=9708) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;border-left-color: #ffffff !important;border-left-style: solid !important;border-right-color: #ffffff !important;border-right-style: solid !important;}&#8221; woodmart_css_id=&#8221;653d19ddd32f2&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NTNkMTlkZGQzMmYyIiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;yes&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243; woodmart_color_gradient=&#8221;rgba(0, 0, 0, 0.3)-0\/rgba(0, 0, 0, 0.3)-100\/|linear-gradient(left , rgba(0, 0, 0, 0.3) , rgba(0, 0, 0, 0.3) 100%)|linear|left&#8221;][vc_column css=&#8221;.vc_custom_1692284849437{margin-right: 0px !important;margin-left: 0px !important;}&#8221; woodmart_css_id=&#8221;64de3793d648a&#8221; parallax_scroll=&#8221;no&#8221; woodmart_sticky_column=&#8221;false&#8221; wd_collapsible_content_switcher=&#8221;no&#8221; wd_column_role_offcanvas_desktop=&#8221;no&#8221; wd_column_role_offcanvas_tablet=&#8221;no&#8221; wd_column_role_offcanvas_mobile=&#8221;no&#8221; wd_column_role_content_desktop=&#8221;no&#8221; wd_column_role_content_tablet=&#8221;no&#8221; wd_column_role_content_mobile=&#8221;no&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_box_shadow=&#8221;no&#8221; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NGRlMzc5M2Q2NDhhIiwic2hvcnRjb2RlIjoidmNfY29sdW1uIiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_reset_margin=&#8221;no&#8221; tablet_reset_margin=&#8221;no&#8221; wd_z_index=&#8221;no&#8221;]\n\t\t<div id=\"wd-6851d4fa78e00\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6851d4fa78e00 wd-title-color-white wd-title-style-default text-center vc_custom_1750193426773 wd-width-enabled wd-underline-colored\" style=\"--wd-max-width: 80%;\">\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"title-subtitle  subtitle-color-white font-default subtitle-style-default wd-font-weight-500 wd-fontsize-xs\">B&amp;B E CASE VACANZA SUI COLLI EUGANEI<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h1 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >FATTORIA BUSA DELL'ORO<\/h1>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child  wd-fontsize-xs\">Tre stanze con bagno privato, angolo cottura, zona notte, tutte rinnovate nel 2023 e tre appartamenti da 50, 55 e 150 mq. La sua posizione consente una magnifica vista panoramica dai Colli Euganei fino alle Prealpi Vicentine.<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[\/vc_column][\/vc_row][vc_section css=&#8221;.vc_custom_1692094404138{margin-top: -40px !important;padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 0px !important;padding-left: 0px !important;}&#8221; woodmart_css_id=&#8221;64db4fae36a03&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NGRiNGZhZTM2YTAzIiwic2hvcnRjb2RlIjoidmNfc2VjdGlvbiIsImRhdGEiOnsidGFibGV0Ijp7fSwibW9iaWxlIjp7fX19&#8243; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243;][vc_row full_width=&#8221;stretch_row&#8221; woodmart_css_id=&#8221;64db8c62747bf&#8221; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NGRiOGM2Mjc0N2JmIiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243; css=&#8221;.vc_custom_1692109936671{margin-top: 30px !important;background-color: #ffffff !important;}&#8221;][vc_column]\n\t\t<div id=\"wd-64e37db2cf465\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-64e37db2cf465 wd-title-color-primary wd-title-style-default text-left vc_custom_1692630632542 wd-underline-colored\">\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"title-subtitle  subtitle-color-primary font-default subtitle-style-default wd-font-weight-300 wd-fontsize-xs\">__ IMMERSA NEL VERDE DEI COLLI EUGANEI<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight-300 wd-fontsize-xxl\" >Scopri La Fattoria<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"wd-64e380320de2e\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-64e380320de2e text-left wd-font-weight-300 wd-fontsize-custom vc_custom_1692631122739\">\n\t\t\t<p>La <strong>Fattoria Busa dell&#8217;Oro B&amp;B<\/strong> si trova in mezzo al rigoglioso <strong>Parco Regionale dei Colli Euganei<\/strong>, precisamente sulle pendici settentrionali del monte Lonzina. Da qui, potrete godere di una vista panoramica mozzafiato sull&#8217;<strong>Abbazia di Praglia<\/strong>, raggiungibile con una breve e piacevole passeggiata lungo il percorso di Sant\u2019Antonio o seguendo l&#8217;anello ciclabile E2 dei Colli Euganei.<\/p>\n<p>Ma le meraviglie non si fermano qui. I nostri ospiti avranno l&#8217;opportunit\u00e0 di creare <strong>itinerari enogastronomici deliziosi<\/strong>, alla scoperta delle tradizioni, delle culture e dei prodotti tipici del territorio. Inoltre, non mancheranno<strong> eventi culturali, mostre e festivit\u00e0 folkloristiche<\/strong> che renderanno il vostro soggiorno ancora pi\u00f9 speciale.<\/p>\n<p>E se desiderate esplorare ulteriormente la zona, troverete a breve distanza dalla struttura alcune gemme locali come <strong>Villa dei Vescovi, il Labirinto di Valsanzibio, il Parco Avventura Le Fiorine, Villa Draghi<\/strong> e molte altre destinazioni imperdibili.<\/p>\n<p>La nostra location offre un <strong>ambiente tranquillo e riservato<\/strong>, in stretto contatto con la natura. \u00c8 l&#8217;ideale per chi desidera trascorrere momenti di completo relax, lontano dal trambusto dei luoghi turistici e dalle frenetiche citt\u00e0.<\/p>\n\t\t<\/div>\n\t\t[\/vc_column][\/vc_row][vc_row woodmart_css_id=&#8221;6532985a34b88&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NTMyOTg1YTM0Yjg4Iiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243;][vc_column]\n\t\t<div id=\"wd-653298434745e\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-653298434745e wd-title-color-primary wd-title-style-default text-left vc_custom_1697814614617 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight-300 wd-fontsize-xxl\" >Photogallery<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"gallery_366\" class=\"wd-images-gallery wd-wpb wd-rs-684acdb628fe1 photoswipe-images\" style=\"--wd-justify-content:center;--wd-align-items:center;\">\n\t\t\t\n\t\t\t<div class=\" wd-grid-g\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:1;--wd-gap-lg:2px;\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-5.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"1\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-5-300x169.jpg\" class=\"wd-gallery-image image-1\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-5-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-5-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-5-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-5-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-5.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-2-1.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"2\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-2-1-300x169.jpg\" class=\"wd-gallery-image image-2\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-2-1-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-2-1-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-2-1-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-2-1-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-2-1.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-4.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"3\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-4-300x169.jpg\" class=\"wd-gallery-image image-3\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-4-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-4-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-4-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-4-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-4.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-3.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"4\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-3-300x169.jpg\" class=\"wd-gallery-image image-4\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-3-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-3-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-3-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-3-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-3.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-21.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"5\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-21-300x169.jpg\" class=\"wd-gallery-image image-5\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-21-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-21-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-21-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-21-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-21.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-22.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"6\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-22-300x169.jpg\" class=\"wd-gallery-image image-6\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-22-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-22-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-22-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-22-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-22.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-20.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"7\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-20-300x169.jpg\" class=\"wd-gallery-image image-7\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-20-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-20-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-20-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-20-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-20.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-19.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"8\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-19-300x169.jpg\" class=\"wd-gallery-image image-8\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-19-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-19-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-19-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-19-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-19.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-17.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"9\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-17-300x169.jpg\" class=\"wd-gallery-image image-9\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-17-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-17-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-17-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-17-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-17.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-14.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"10\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-14-300x169.jpg\" class=\"wd-gallery-image image-10\" alt=\"bed and breakfast fattoria Busa dell&#039;Oro\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-14-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-14-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-14-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-14-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-14.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-11-1.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"11\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-11-1-300x169.jpg\" class=\"wd-gallery-image image-11\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-11-1-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-11-1-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-11-1-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-11-1-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-11-1.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-15.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"12\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-15-300x169.jpg\" class=\"wd-gallery-image image-12\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-15-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-15-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-15-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-15-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-15.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-6.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"13\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-6-300x169.jpg\" class=\"wd-gallery-image image-13\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-6-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-6-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-6-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-6-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-6.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-10.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"14\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-10-300x169.jpg\" class=\"wd-gallery-image image-14\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-10-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-10-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-10-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-10-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-10.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-16.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"15\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-16-300x169.jpg\" class=\"wd-gallery-image image-15\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-16-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-16-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-16-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-16-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-16.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-18.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"16\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-18-300x169.jpg\" class=\"wd-gallery-image image-16\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-18-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-18-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-18-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-18-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-18.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-8.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"17\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-8-300x169.jpg\" class=\"wd-gallery-image image-17\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-8-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-8-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-8-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-8-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-8.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-23.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"18\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-23-300x169.jpg\" class=\"wd-gallery-image image-18\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-23-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-23-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-23-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-23-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-23.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-9-1.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"19\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-9-1-300x169.jpg\" class=\"wd-gallery-image image-19\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-9-1-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-9-1-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-9-1-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-9-1-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-9-1.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-12.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"20\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-12-300x169.jpg\" class=\"wd-gallery-image image-20\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-12-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-12-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-12-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-12-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-12.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-1.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"21\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-1-300x169.jpg\" class=\"wd-gallery-image image-21\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-1-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-1-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-1-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-1-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/BUSA-ESTERNO-2023-1.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0402.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"22\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0402-300x169.jpg\" class=\"wd-gallery-image image-22\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0402-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0402-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0402-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0402-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0402.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0393.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"23\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0393-300x169.jpg\" class=\"wd-gallery-image image-23\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0393-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0393-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0393-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0393-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0393.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0383.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"24\" data-width=\"1920\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0383-300x169.jpg\" class=\"wd-gallery-image image-24\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0383-300x169.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0383-1024x576.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0383-768x432.jpg 768w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0383-1536x864.jpg 1536w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/10\/PRF_0383.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;top&#8221; woodmart_css_id=&#8221;64e4803c93815&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NGU0ODAzYzkzODE1Iiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243; css=&#8221;.vc_custom_1692696683619{margin-top: 20px !important;border-right-width: 10px !important;border-bottom-width: 10px !important;border-left-width: 10px !important;padding-top: 0px !important;padding-bottom: 0px !important;background-color: #f7f7f7 !important;border-left-color: #ffffff !important;border-left-style: solid !important;border-right-color: #ffffff !important;border-right-style: solid !important;border-bottom-color: #ffffff !important;border-bottom-style: solid !important;}&#8221;][vc_column]\n\t\t<div id=\"wd-64e472c31c5cb\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-64e472c31c5cb wd-title-color-primary wd-title-style-default text-left vc_custom_1692693234202 wd-underline-colored\">\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"title-subtitle  subtitle-color-primary font-default subtitle-style-default wd-font-weight-300 wd-fontsize-xs\">__ LA LEGGENDA<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight-300 wd-fontsize-xxl\" >Perch\u00e8 Busa dell'Oro?<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"wd-64e4812d22dbd\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-64e4812d22dbd text-left wd-font-weight-300 wd-fontsize-custom \">\n\t\t\t<p>Busa dell\u2019Oro, o anche chiamata buca dell\u2019Oro, trae origine da un&#8217;antica e affascinante leggenda locale. Narra la storia di un valoroso soldato di ventura, che prestava servizio sotto il feroce signore duecentesco Ezzelino da Romano. Stanco delle continue guerre e delle devastazioni, il soldato decise di disertare e fuggire dalle fila del condottiero.<\/p>\n<p>Inseguito implacabilmente dagli uomini di Ezzelino, si rifugi\u00f2 tra le aspre colline dei nostri Colli Euganei. In un atto di furbizia, riusc\u00ec a nascondere il ricco bottino accumulato durante molte battaglie in una buca segreta, che poi si preoccup\u00f2 di occultare con cura.<\/p>\n<p>Nonostante venisse raggiunto e morisse combattendo per evitare la prigionia, port\u00f2 con s\u00e9 il segreto della posizione in cui aveva nascosto l&#8217;oro. Da quel momento, nonostante svariati tentativi, il tesoro non \u00e8 mai stato rinvenuto e giace ancora oggi, nascosto da qualche parte, in attesa di tornare alla luce.<\/p>\n<p>La leggenda della Busa dell\u2019Oro incarna il mistero e l&#8217;incanto di questi luoghi, pronti a svelare i loro segreti a chiunque sia disposto a cercare.<\/p>\n\t\t<\/div>\n\t\t[\/vc_column][\/vc_row][\/vc_section][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; content_placement=&#8221;middle&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243; woodmart_disable_overflow=&#8221;0&#8243; css=&#8221;.vc_custom_1697812995131{margin-top: 0px !important;margin-bottom: 10px !important;border-right-width: 10px !important;border-bottom-width: 10px !important;border-left-width: 10px !important;padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 0px !important;padding-left: 0px !important;background-color: #136d3d !important;border-left-color: #ffffff !important;border-left-style: solid !important;border-right-color: #ffffff !important;border-right-style: solid !important;border-bottom-color: #ffffff !important;border-bottom-style: solid !important;}&#8221; woodmart_css_id=&#8221;653291f5c81af&#8221; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NTMyOTFmNWM4MWFmIiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221;][vc_column width=&#8221;1\/2&#8243; horizontal_alignment=&#8221;eyJkZXZpY2VzIjp7ImRlc2t0b3AiOnsidmFsdWUiOiJjZW50ZXIifSwidGFibGV0Ijp7InZhbHVlIjoiIn0sIm1vYmlsZSI6eyJ2YWx1ZSI6IiJ9fX0=&#8221; woodmart_bg_position=&#8221;center-center&#8221; css=&#8221;.vc_custom_1692090690908{border-right-width: 10px !important;padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 0px !important;padding-left: 0px !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;border-right-color: #ffffff !important;border-right-style: solid !important;}&#8221; woodmart_parallax=&#8221;0&#8243; parallax_scroll=&#8221;no&#8221; woodmart_sticky_column=&#8221;false&#8221; offset=&#8221;vc_col-lg-8 vc_col-md-6 vc_col-sm-offset-0 vc_col-xs-12&#8243; woodmart_css_id=&#8221;64db413291cc7&#8243; wd_collapsible_content_switcher=&#8221;no&#8221; wd_column_role_offcanvas_desktop=&#8221;no&#8221; wd_column_role_offcanvas_tablet=&#8221;no&#8221; wd_column_role_offcanvas_mobile=&#8221;no&#8221; wd_column_role_content_desktop=&#8221;no&#8221; wd_column_role_content_tablet=&#8221;no&#8221; wd_column_role_content_mobile=&#8221;no&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NGRiNDEzMjkxY2M3Iiwic2hvcnRjb2RlIjoidmNfY29sdW1uIiwiZGF0YSI6eyJ0YWJsZXQiOnsiYm9yZGVyLXJpZ2h0LXdpZHRoIjoiMHB4In0sIm1vYmlsZSI6e319fQ==&#8221; mobile_reset_margin=&#8221;no&#8221; tablet_reset_margin=&#8221;no&#8221; wd_z_index=&#8221;no&#8221;]\t\t<div class=\"promo-banner-wrapper  wd-rs-64e47f579e0cd \">\n\t\t\t\t\t\t<div id=\"wd-64e47f579e0cd\" class=\"promo-banner  banner- banner-hover-none color-scheme-light banner-btn-size-default banner-btn-style-default  wd-underline-colored\">\n\t\t\t\t<div class=\"main-wrapp-img\">\n\t\t\t\t\t<div class=\"banner-image wd-bg-position-center\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"500\" src=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/08\/olive.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/08\/olive.jpg 1300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/08\/olive-300x115.jpg 300w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/08\/olive-1024x394.jpg 1024w, https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/08\/olive-768x295.jpg 768w\" sizes=\"auto, (max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wrapper-content-banner wd-fill  wd-items-top wd-justify-left\">\n\t\t\t\t\t<div class=\"content-banner  text-left\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t[\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1692697378426{margin-top: 0px !important;margin-right: 150px !important;margin-bottom: 0px !important;margin-left: -120px !important;padding-top: 4% !important;padding-right: 7% !important;padding-bottom: 4% !important;padding-left: 7% !important;background-color: rgba(255,255,255,0.95) !important;*background-color: rgb(255,255,255) !important;}&#8221; woodmart_parallax=&#8221;0&#8243; parallax_scroll=&#8221;no&#8221; woodmart_sticky_column=&#8221;false&#8221; offset=&#8221;vc_col-lg-4 vc_col-md-6 vc_col-xs-12&#8243; woodmart_css_id=&#8221;64e4831a30733&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NGU0ODMxYTMwNzMzIiwic2hvcnRjb2RlIjoidmNfY29sdW1uIiwiZGF0YSI6eyJ0YWJsZXQiOnsibWFyZ2luLXJpZ2h0IjoiMTVweCIsIm1hcmdpbi1sZWZ0IjoiMTVweCIsInBhZGRpbmctdG9wIjoiMiUiLCJwYWRkaW5nLXJpZ2h0IjoiNyUiLCJwYWRkaW5nLWJvdHRvbSI6IjIlIiwicGFkZGluZy1sZWZ0IjoiNyUifSwibW9iaWxlIjp7Im1hcmdpbi10b3AiOiIxMHB4IiwibWFyZ2luLXJpZ2h0IjoiMTBweCIsIm1hcmdpbi1ib3R0b20iOiIxMHB4IiwibWFyZ2luLWxlZnQiOiIxMHB4In19fQ==&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; mobile_reset_margin=&#8221;yes&#8221; tablet_reset_margin=&#8221;yes&#8221; wd_collapsible_content_switcher=&#8221;no&#8221; wd_column_role_offcanvas_desktop=&#8221;no&#8221; wd_column_role_offcanvas_tablet=&#8221;no&#8221; wd_column_role_offcanvas_mobile=&#8221;no&#8221; wd_column_role_content_desktop=&#8221;no&#8221; wd_column_role_content_tablet=&#8221;no&#8221; wd_column_role_content_mobile=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221;]\n\t\t<div id=\"wd-64e47aa9eeaa1\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-64e47aa9eeaa1 wd-title-color-primary wd-title-style-simple text-center vc_custom_1692695220467 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight-300 wd-fontsize-xxl\" >La nostra Produzione<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"wd-64e47aed91ada\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-64e47aed91ada text-center wd-fontsize-custom \">\n\t\t\t<p>La Fattoria Busa dell&#8217;Oro si caratterizza per la sua rigogliosa vegetazione, che comprende <strong>castagni, vari alberi da frutto e ulivi<\/strong>.<\/p>\n<p>Ogni anno, nel mese di novembre, raccoglie in media <strong>600 kg di olive<\/strong>, che vengono lavorate in modo tradizionale tramite macine in pietra. Questo processo artigianale d\u00e0 vita all&#8217;<strong>Olio Extra Vergine di Oliva &#8220;Fattoria Busa dell&#8217;Oro&#8221;<\/strong>, ottenuto a freddo e caratterizzato da un profumo delicato.<\/p>\n\t\t<\/div>\n\t\t[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; full_height=&#8221;yes&#8221; equal_height=&#8221;yes&#8221; woodmart_bg_position=&#8221;center-top&#8221; css=&#8221;.vc_custom_1698503145965{margin-top: -40px !important;margin-right: 0px !important;margin-left: 0px !important;border-right-width: 10px !important;border-left-width: 10px !important;padding-top: 20px !important;padding-bottom: 20px !important;background-image:<\/p>\n","protected":false},"author":7,"featured_media":8502,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8827","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>B&amp;B Fattoria Busa dell&#039;Oro - Teolo - Parco Colli Euganei - Padova<\/title>\n<meta name=\"description\" content=\"Fattoria Busa dell&#039;Oro B&amp;B \u00e8 immersa nel verde del Parco Regionale dei Colli Euganei. I nostri ospiti avranno la possibilit\u00e0 di costruire golosi itinerari enogastronomici attraverso i quali scoprire tradizioni e culture, i prodotti tipici del territorio, oltre a poter praticare diversi Sport ed Escursioni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/labusadelloro.com\/it\/la-fattoria\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"B&amp;B Fattoria Busa dell&#039;Oro - Teolo - Parco Colli Euganei - Padova\" \/>\n<meta name=\"twitter:description\" content=\"Fattoria Busa dell&#039;Oro B&amp;B \u00e8 immersa nel verde del Parco Regionale dei Colli Euganei. I nostri ospiti avranno la possibilit\u00e0 di costruire golosi itinerari enogastronomici attraverso i quali scoprire tradizioni e culture, i prodotti tipici del territorio, oltre a poter praticare diversi Sport ed Escursioni.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/08\/busa.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/labusadelloro.com\\\/it\\\/la-fattoria\\\/\",\"url\":\"https:\\\/\\\/labusadelloro.com\\\/it\\\/la-fattoria\\\/\",\"name\":\"B&B Fattoria Busa dell'Oro - Teolo - Parco Colli Euganei - Padova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/labusadelloro.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/labusadelloro.com\\\/it\\\/la-fattoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/labusadelloro.com\\\/it\\\/la-fattoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/labusadelloro.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/busa.jpg\",\"datePublished\":\"2023-08-21T15:03:23+00:00\",\"dateModified\":\"2026-07-17T12:43:57+00:00\",\"description\":\"Fattoria Busa dell'Oro B&B \u00e8 immersa nel verde del Parco Regionale dei Colli Euganei. I nostri ospiti avranno la possibilit\u00e0 di costruire golosi itinerari enogastronomici attraverso i quali scoprire tradizioni e culture, i prodotti tipici del territorio, oltre a poter praticare diversi Sport ed Escursioni.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/labusadelloro.com\\\/it\\\/la-fattoria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/labusadelloro.com\\\/it\\\/la-fattoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/labusadelloro.com\\\/it\\\/la-fattoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/labusadelloro.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/busa.jpg\",\"contentUrl\":\"https:\\\/\\\/labusadelloro.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/busa.jpg\",\"width\":1300,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/labusadelloro.com\\\/it\\\/la-fattoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/labusadelloro.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fattoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/labusadelloro.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/labusadelloro.com\\\/it\\\/\",\"name\":\"Fattoria Busa dell&#039;Oro\",\"description\":\"Bed and Breakfast Colli Euganei\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/labusadelloro.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B&B Fattoria Busa dell'Oro - Teolo - Parco Colli Euganei - Padova","description":"Fattoria Busa dell'Oro B&B \u00e8 immersa nel verde del Parco Regionale dei Colli Euganei. I nostri ospiti avranno la possibilit\u00e0 di costruire golosi itinerari enogastronomici attraverso i quali scoprire tradizioni e culture, i prodotti tipici del territorio, oltre a poter praticare diversi Sport ed Escursioni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/labusadelloro.com\/it\/la-fattoria\/","twitter_card":"summary_large_image","twitter_title":"B&B Fattoria Busa dell'Oro - Teolo - Parco Colli Euganei - Padova","twitter_description":"Fattoria Busa dell'Oro B&B \u00e8 immersa nel verde del Parco Regionale dei Colli Euganei. I nostri ospiti avranno la possibilit\u00e0 di costruire golosi itinerari enogastronomici attraverso i quali scoprire tradizioni e culture, i prodotti tipici del territorio, oltre a poter praticare diversi Sport ed Escursioni.","twitter_image":"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/08\/busa.jpg","twitter_misc":{"Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/labusadelloro.com\/it\/la-fattoria\/","url":"https:\/\/labusadelloro.com\/it\/la-fattoria\/","name":"B&B Fattoria Busa dell'Oro - Teolo - Parco Colli Euganei - Padova","isPartOf":{"@id":"https:\/\/labusadelloro.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/labusadelloro.com\/it\/la-fattoria\/#primaryimage"},"image":{"@id":"https:\/\/labusadelloro.com\/it\/la-fattoria\/#primaryimage"},"thumbnailUrl":"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/08\/busa.jpg","datePublished":"2023-08-21T15:03:23+00:00","dateModified":"2026-07-17T12:43:57+00:00","description":"Fattoria Busa dell'Oro B&B \u00e8 immersa nel verde del Parco Regionale dei Colli Euganei. I nostri ospiti avranno la possibilit\u00e0 di costruire golosi itinerari enogastronomici attraverso i quali scoprire tradizioni e culture, i prodotti tipici del territorio, oltre a poter praticare diversi Sport ed Escursioni.","breadcrumb":{"@id":"https:\/\/labusadelloro.com\/it\/la-fattoria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/labusadelloro.com\/it\/la-fattoria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/labusadelloro.com\/it\/la-fattoria\/#primaryimage","url":"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/08\/busa.jpg","contentUrl":"https:\/\/labusadelloro.com\/wp-content\/uploads\/2023\/08\/busa.jpg","width":1300,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/labusadelloro.com\/it\/la-fattoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/labusadelloro.com\/it\/"},{"@type":"ListItem","position":2,"name":"La Fattoria"}]},{"@type":"WebSite","@id":"https:\/\/labusadelloro.com\/it\/#website","url":"https:\/\/labusadelloro.com\/it\/","name":"Fattoria Busa dell&#039;Oro","description":"Bed and Breakfast Colli Euganei","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/labusadelloro.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/labusadelloro.com\/it\/wp-json\/wp\/v2\/pages\/8827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labusadelloro.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/labusadelloro.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/labusadelloro.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/labusadelloro.com\/it\/wp-json\/wp\/v2\/comments?post=8827"}],"version-history":[{"count":2,"href":"https:\/\/labusadelloro.com\/it\/wp-json\/wp\/v2\/pages\/8827\/revisions"}],"predecessor-version":[{"id":10684,"href":"https:\/\/labusadelloro.com\/it\/wp-json\/wp\/v2\/pages\/8827\/revisions\/10684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labusadelloro.com\/it\/wp-json\/wp\/v2\/media\/8502"}],"wp:attachment":[{"href":"https:\/\/labusadelloro.com\/it\/wp-json\/wp\/v2\/media?parent=8827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}